{"id":884,"date":"2018-09-23T09:32:35","date_gmt":"2018-09-23T09:32:35","guid":{"rendered":"http:\/\/sitaleon.fr\/blog\/?p=884"},"modified":"2018-09-23T13:09:56","modified_gmt":"2018-09-23T13:09:56","slug":"conclusion","status":"publish","type":"post","link":"http:\/\/sitaleon.fr\/blog\/2018\/09\/23\/conclusion\/","title":{"rendered":"Conclusion"},"content":{"rendered":"<p>On trimballe une quantit\u00e9 de trucs impressionnante :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-887 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/IMG_0418-1.jpg\" alt=\"\" width=\"1333\" height=\"1778\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/IMG_0418-1.jpg 1333w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/IMG_0418-1-225x300.jpg 225w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/IMG_0418-1-768x1024.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>et souvent inutile&#8230;&#8230;.<\/p>\n<p>Le Duster s&rsquo;est bien tenu et la bonne surprise a \u00e9t\u00e9 une consommation de 7,90 litres malgr\u00e9 la remorque (contre 11 bons gros litres pour le vieux katkat)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-668 size-full aligncenter\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0154.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0154.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0154-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0154-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0154-1024x683.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Le cantal, La Loz\u00e8re, le lac de Salagou, les gorges du Tarn, de l\u2019H\u00e9rault, de la Jonte, du Tarnon&#8230;.. Que du bonheur !<\/p>\n<p>Les H\u00e9bergements :<\/p>\n<p>A Naussac : Les terrasses du Lac. Chouette emplacement, avec vue sur le lac. Le petit chalet en bois \u00e9tait bien vieillot par rapport \u00e0 ce qui est montr\u00e9 sur le site internet. Les sanitaires communes avec les autres chalets (mais propres).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-888 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0013.jpg\" alt=\"\" width=\"1200\" height=\"798\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0013.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0013-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0013-768x511.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0013-1024x681.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>A Florac : Camping le pont du Tarn. On y \u00e9tait tellement bien qu&rsquo;on y est retourn\u00e9. Tr\u00e8s chouette bungalow, super localisation. Accueil sympa. Tout pour plaire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-889 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/41688336_2074624349238098_4943601438954618880_n.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/41688336_2074624349238098_4943601438954618880_n.jpg 960w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/41688336_2074624349238098_4943601438954618880_n-300x225.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/41688336_2074624349238098_4943601438954618880_n-768x576.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Lac de Salagou : Camping club Lac du Salagou (4* ?) . On avait choisi un 4 \u00e9toiles pour \u00eatre tranquilles&#8230;. Les Sanitaires \u00e9taient plus que limite. A tel point qu&rsquo;on avait pr\u00e9vu de camper et qu&rsquo;au bout d&rsquo;une nuit, on a d\u00e9m\u00e9nag\u00e9 vers un bungalow. D&rsquo;autre part, compte tenu de la localisation, beaucoup de locaux viennent en week-end. Du bruit, de la musique forte. Bref l&rsquo;ambiance des bords de mer que l&rsquo;on aime pas. Je m\u2019aper\u00e7ois que je n&rsquo;ai m\u00eame pas pris de photos, c&rsquo;est dire&#8230;..<\/p>\n<p>Pour conclure, tr\u00e8s chouettes vacances, avec de supers paysages, un temps de r\u00eave, pas une goutte d&rsquo;eau, presque trop chaud (surtout \u00e0 Salagou).<\/p>\n<p><strong>On repart quand ?<br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On trimballe une quantit\u00e9 de trucs impressionnante : et souvent inutile&#8230;&#8230;. Le Duster s&rsquo;est bien tenu et la bonne surprise a \u00e9t\u00e9 une consommation de 7,90 litres malgr\u00e9 la remorque (contre 11 bons gros litres pour le vieux katkat) Le cantal, La Loz\u00e8re, le lac de Salagou, les gorges du Tarn, de l\u2019H\u00e9rault, de la &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/sitaleon.fr\/blog\/2018\/09\/23\/conclusion\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Conclusion&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-884","post","type-post","status-publish","format-standard","hentry","category-photos-de-vacances"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/884"}],"collection":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/comments?post=884"}],"version-history":[{"count":8,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/884\/revisions"}],"predecessor-version":[{"id":896,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/884\/revisions\/896"}],"wp:attachment":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/media?parent=884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/categories?post=884"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/tags?post=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}