{"id":701,"date":"2018-09-11T17:51:27","date_gmt":"2018-09-11T17:51:27","guid":{"rendered":"http:\/\/sitaleon.fr\/blog\/?p=701"},"modified":"2018-09-11T18:26:04","modified_gmt":"2018-09-11T18:26:04","slug":"jour-3","status":"publish","type":"post","link":"http:\/\/sitaleon.fr\/blog\/2018\/09\/11\/jour-3\/","title":{"rendered":"Jour 3"},"content":{"rendered":"<p>Liaison Langogne-Florac en passant par Mende ou nous avons trouv\u00e9 une batterie \ud83d\ude42<\/p>\n<p>Repas tr\u00e8s sympa chez un copain de katkat de G\u00e9rard, ils vivent dans un endroit fabuleux<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-703 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0200.jpg\" alt=\"\" width=\"1200\" height=\"863\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0200.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0200-300x216.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0200-768x552.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0200-1024x736.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-702 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0198.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0198.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0198-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0198-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2018\/09\/DSC_0198-1024x683.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>et ce soir, \u00e7\u00e0 charge \ud83d\ude42 (<em>pour la d\u00e9charge, on en reparle demain<\/em>) LOL<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liaison Langogne-Florac en passant par Mende ou nous avons trouv\u00e9 une batterie \ud83d\ude42 Repas tr\u00e8s sympa chez un copain de katkat de G\u00e9rard, ils vivent dans un endroit fabuleux et ce soir, \u00e7\u00e0 charge \ud83d\ude42 (pour la d\u00e9charge, on en reparle demain) LOL &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-701","post","type-post","status-publish","format-standard","hentry","category-photos-de-vacances"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/701"}],"collection":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/comments?post=701"}],"version-history":[{"count":2,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/701\/revisions"}],"predecessor-version":[{"id":706,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/701\/revisions\/706"}],"wp:attachment":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/media?parent=701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/categories?post=701"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/tags?post=701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}