{"id":4455,"date":"2025-06-03T06:25:11","date_gmt":"2025-06-03T06:25:11","guid":{"rendered":"https:\/\/sitaleon.fr\/blog\/?p=4455"},"modified":"2025-06-03T06:28:45","modified_gmt":"2025-06-03T06:28:45","slug":"2-juin-pluie-pluie-pluie","status":"publish","type":"post","link":"http:\/\/sitaleon.fr\/blog\/2025\/06\/03\/2-juin-pluie-pluie-pluie\/","title":{"rendered":"2 Juin &#8211; Pluie pluie pluie"},"content":{"rendered":"\n<p>Comme l&rsquo;indique le titre, il pleut, ce qui n&rsquo;encourage pas trop la balade, la photo.<\/p>\n\n\n\n<p>Pour couronner le tout, dimanche soir j&rsquo;ai voulu photographier les orages, et le slot sd de mon fid\u00e8le D500 a l\u00e2ch\u00e9. Il me reste le slot QXD mais pas la carte kivabien. En local, on a pas trouv\u00e9, commande faite chez un GAFAM&#8230; On croise les doigts pour que cela arrive, pas trop tard dans la semaine.<\/p>\n\n\n\n<p>Il me reste le D7500 increvable, en attendant. M\u00eame qu&rsquo;il sait faire des clich\u00e9s sous la pluie \ud83d\ude09 <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1336-1024x683.jpg\" alt=\"\" class=\"wp-image-4456\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1336-1024x683.jpg 1024w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1336-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1336-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1336.jpg 1500w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"793\" height=\"1000\" src=\"https:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1337.jpg\" alt=\"\" class=\"wp-image-4457\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1337.jpg 793w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1337-238x300.jpg 238w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/06\/DSC_1337-768x968.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Ca serait mieux sous le soleil, non ?<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme l&rsquo;indique le titre, il pleut, ce qui n&rsquo;encourage pas trop la balade, la photo. Pour couronner le tout, dimanche soir j&rsquo;ai voulu photographier les orages, et le slot sd de mon fid\u00e8le D500 a l\u00e2ch\u00e9. Il me reste le slot QXD mais pas la carte kivabien. En local, on a pas trouv\u00e9, commande faite &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/sitaleon.fr\/blog\/2025\/06\/03\/2-juin-pluie-pluie-pluie\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;2 Juin &#8211; Pluie pluie pluie&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4455","post","type-post","status-publish","format-standard","hentry","category-photos-de-vacances"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/4455"}],"collection":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/comments?post=4455"}],"version-history":[{"count":2,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/4455\/revisions"}],"predecessor-version":[{"id":4459,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/4455\/revisions\/4459"}],"wp:attachment":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/media?parent=4455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/categories?post=4455"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/tags?post=4455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}