{"id":4289,"date":"2025-02-20T05:56:29","date_gmt":"2025-02-20T05:56:29","guid":{"rendered":"http:\/\/sitaleon.fr\/blog\/?p=4289"},"modified":"2025-02-20T05:56:29","modified_gmt":"2025-02-20T05:56:29","slug":"quelques-jours-imprevus","status":"publish","type":"post","link":"http:\/\/sitaleon.fr\/blog\/2025\/02\/20\/quelques-jours-imprevus\/","title":{"rendered":"Quelques jours Impr\u00e9vus"},"content":{"rendered":"\n<p>On ze road again. Avec la diff\u00e9rence que la semaine derni\u00e8re on ne le savait pas.<\/p>\n\n\n\n<p>Nous sommes en direction de la Bretagne parce que la Tantine de L\u00e9on a d\u00e9cid\u00e9 de prendre sa retraite \u00e9ternelle, et on a pas envie de la laisser partir seule.<\/p>\n\n\n\n<p>Impr\u00e9vu, donc. Et pas le seul, on vous raconte \u00e7a quand nous serons arriv\u00e9s, si on a un peu de temps. Enfin oui on le prendra le temps ;). En attendant, jamais sans mon apn, une petite photo de bord de route !<\/p>\n\n\n\n<p>A+, on a de la route \u00e0 faire <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4290\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/02\/DSC_5533-1024x683.jpg\" alt=\"\" class=\"wp-image-4290\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/02\/DSC_5533-1024x683.jpg 1024w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/02\/DSC_5533-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/02\/DSC_5533-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2025\/02\/DSC_5533.jpg 1500w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>On ze road again. Avec la diff\u00e9rence que la semaine derni\u00e8re on ne le savait pas. Nous sommes en direction de la Bretagne parce que la Tantine de L\u00e9on a d\u00e9cid\u00e9 de prendre sa retraite \u00e9ternelle, et on a pas envie de la laisser partir seule. Impr\u00e9vu, donc. Et pas le seul, on vous raconte &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/sitaleon.fr\/blog\/2025\/02\/20\/quelques-jours-imprevus\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Quelques jours Impr\u00e9vus&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4289","post","type-post","status-publish","format-standard","hentry","category-photos-de-vacances"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/4289"}],"collection":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/comments?post=4289"}],"version-history":[{"count":2,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/4289\/revisions"}],"predecessor-version":[{"id":4292,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/4289\/revisions\/4292"}],"wp:attachment":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/media?parent=4289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/categories?post=4289"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/tags?post=4289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}