{"id":2209,"date":"2021-09-02T06:46:10","date_gmt":"2021-09-02T06:46:10","guid":{"rendered":"http:\/\/sitaleon.fr\/blog\/?p=2209"},"modified":"2021-09-02T06:46:10","modified_gmt":"2021-09-02T06:46:10","slug":"nuit-du-1er-au-2-septembre","status":"publish","type":"post","link":"http:\/\/sitaleon.fr\/blog\/2021\/09\/02\/nuit-du-1er-au-2-septembre\/","title":{"rendered":"Nuit du 1er au 2 septembre"},"content":{"rendered":"<p>Le ciel est tellement joli la nuit ! Tr\u00e8s peu de pollution lumineuse et un terrain de jeu infini sur la mer.<\/p>\n<p>Alors hier soir j&rsquo;ai train\u00e9 mon p&rsquo;tit Leon, pour la deuxi\u00e8me fois des vacances sur les plages du coin.<\/p>\n<p>La pointe de Trevignon :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2210 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1654.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1654.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1654-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1654-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1654-1024x683.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Autre version :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2211 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1665.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1665.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1665-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1665-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1665-1024x683.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>la Plage de Raguenez<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2212 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1691.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1691.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1691-300x200.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1691-768x512.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1691-1024x683.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>autre version :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2213 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1697.jpg\" alt=\"\" width=\"667\" height=\"1000\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1697.jpg 667w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1697-200x300.jpg 200w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/p>\n<p>Quoi qu&rsquo;il en soit je remercie mon petit mari de me suivre dans mes d\u00e9lires photographiques. Le pauvre il souffre du froid, du vent, du manque de sommeil \ud83d\ude09<\/p>\n<p>clich\u00e9 pris hier soir : 17 degr\u00e9s dehors, il avait une polaire, son blouson de moto, une \u00e9charpe&#8230;&#8230;. tout en \u00e9tant dans la voiture&#8230;&#8230; \ud83d\ude42 \ud83d\ude42 \ud83d\ude42 sacr\u00e9 L\u00e9on.\u00a0 Je ne t&rsquo;aurais pas je t&rsquo;inventerai \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2214 size-full\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1700.jpg\" alt=\"\" width=\"1200\" height=\"744\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1700.jpg 1200w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1700-300x186.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1700-768x476.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2021\/09\/DSC_1700-1024x635.jpg 1024w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ciel est tellement joli la nuit ! Tr\u00e8s peu de pollution lumineuse et un terrain de jeu infini sur la mer. Alors hier soir j&rsquo;ai train\u00e9 mon p&rsquo;tit Leon, pour la deuxi\u00e8me fois des vacances sur les plages du coin. La pointe de Trevignon : Autre version : la Plage de Raguenez autre version &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/sitaleon.fr\/blog\/2021\/09\/02\/nuit-du-1er-au-2-septembre\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Nuit du 1er au 2 septembre&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2209","post","type-post","status-publish","format-standard","hentry","category-photos-de-vacances"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/2209"}],"collection":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/comments?post=2209"}],"version-history":[{"count":1,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/2209\/revisions"}],"predecessor-version":[{"id":2215,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/2209\/revisions\/2215"}],"wp:attachment":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/media?parent=2209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/categories?post=2209"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/tags?post=2209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}