{"id":1,"date":"2017-08-11T04:18:27","date_gmt":"2017-08-11T04:18:27","guid":{"rendered":"http:\/\/sitaleon.fr\/blog\/?p=1"},"modified":"2017-08-11T08:45:58","modified_gmt":"2017-08-11T08:45:58","slug":"hello-world","status":"publish","type":"post","link":"http:\/\/sitaleon.fr\/blog\/2017\/08\/11\/hello-world\/","title":{"rendered":"Ca se pr\u00e9cise !"},"content":{"rendered":"<p>J-2 : Nous nous sommes enfin mis d&rsquo;accord sur une destination, apr\u00e8s avoir envisag\u00e9 pas mal de lieux diff\u00e9rents. Il semblerait que nous prenions la route des pays des Balkans. Lesquels ? affaire \u00e0 suivre \ud83d\ude09<\/p>\n<p>En attendant, nous avons ressorti le stock de cartes \ud83d\ude42<\/p>\n<figure id=\"attachment_13\" aria-describedby=\"caption-attachment-13\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13 size-large\" src=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2017\/08\/341218_248993608467857_4566209_o-1024x768.jpg\" alt=\"\" width=\"525\" height=\"394\" srcset=\"http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2017\/08\/341218_248993608467857_4566209_o-1024x768.jpg 1024w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2017\/08\/341218_248993608467857_4566209_o-300x225.jpg 300w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2017\/08\/341218_248993608467857_4566209_o-768x576.jpg 768w, http:\/\/sitaleon.fr\/blog\/wp-content\/uploads\/2017\/08\/341218_248993608467857_4566209_o.jpg 2048w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-13\" class=\"wp-caption-text\">cartes routi\u00e8res en stock<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J-2 : Nous nous sommes enfin mis d&rsquo;accord sur une destination, apr\u00e8s avoir envisag\u00e9 pas mal de lieux diff\u00e9rents. Il semblerait que nous prenions la route des pays des Balkans. Lesquels ? affaire \u00e0 suivre \ud83d\ude09 En attendant, nous avons ressorti le stock de cartes \ud83d\ude42 &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-photos-de-vacances"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":3,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":14,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/posts\/1\/revisions\/14"}],"wp:attachment":[{"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitaleon.fr\/blog\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}